{"id":7864,"date":"2026-07-02T09:40:44","date_gmt":"2026-07-02T07:40:44","guid":{"rendered":"https:\/\/ratpconnect.com\/?page_id=7864"},"modified":"2026-07-02T10:14:36","modified_gmt":"2026-07-02T08:14:36","slug":"fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante","status":"publish","type":"page","link":"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/","title":{"rendered":"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9"},"content":{"rendered":"<div class=\"gb-container gb-container-ec254eff page-title\">\n\n<h1 class=\"wp-block-heading page-title__heading\"><strong><strong><strong>Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9<\/strong><\/strong><\/strong><\/h1>\n\n<\/div>\n\n<div class=\"breadcrumbs align wp-block-bcn-breadcrumb-trail has-text-color has-background\" vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\">\n\t<span><\/span>\n\t<span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" href=\"https:\/\/ratpconnect.com\/fr\/\" class=\"home\" aria-current=\"page\"><span property=\"name\">Accueil<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div>\n\n\n<div class=\"gb-container gb-container-bbacd815 bandeau-intro\">\n<div class=\"gb-container gb-container-7387bdc5 bandeau-intro__inside\">\n\n<h2 class=\"wp-block-heading mb-0 color-base-3\"><strong><strong><strong><strong>Une connectivit\u00e9 critique au service de la continuit\u00e9 des soins<\/strong><\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p class=\"mb-0 color-base-3 wp-block-paragraph\">RATP Connect accompagne les \u00e9tablissements de sant\u00e9 avec une infrastructure de fibre optique noire, con\u00e7ue pour soutenir les usages num\u00e9riques critiques, s\u00e9curiser les \u00e9changes de donn\u00e9es sensibles et garantir la continuit\u00e9 des services au b\u00e9n\u00e9fice des patients.<\/p>\n\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-fa1abc0b\">\n<div class=\"gb-container gb-container-9d52252c img-block-right__container\">\n<div class=\"gb-container gb-container-836548f9 img-block-right__sub-container\">\n<div class=\"gb-container gb-container-4ccd2a2c img-block-right__image-wrapper\">\n<div class=\"gb-container gb-container-b4ae217c img-block-right__image-container\">\n<div class=\"gb-container gb-container-7844d655 img-block-right__image-content box-shadow--rounded--secondary\">\n\n<figure class=\"gb-block-image gb-block-image-5e078d94\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" class=\"gb-image gb-image-5e078d94 img-block-right__image\" src=\"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg\" alt=\"\" title=\"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9\" srcset=\"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg 1280w, https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante-300x169.jpg 300w, https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante-1024x576.jpg 1024w, https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante-768x432.jpg 768w, https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante-18x10.jpg 18w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-13011404 img-block-right__content border-line-full-page--right--primary\">\n<div class=\"gb-container gb-container-6513a29d img-block-right__header\">\n<div class=\"gb-container gb-container-4cedf3e1 img-block-right__header-content\">\n<div class=\"gb-container gb-container-a4a45e5c img-block-right__text-container\">\n\n<h3 class=\"wp-block-heading block-text-right__subtitle mb-0\"><strong><strong>Soutenir les usages num\u00e9riques de sant\u00e9<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">RATP Connect&nbsp;met \u00e0 disposition des&nbsp;\u00e9tablissements de sant\u00e9,&nbsp;une infrastructure&nbsp;de fibre optique noire fiable, s\u00e9curis\u00e9e et \u00e9volutive, con\u00e7ue pour&nbsp;accompagner leurs&nbsp;usages num\u00e9riques essentiels : dossiers patients, imagerie m\u00e9dicale, t\u00e9l\u00e9m\u00e9decine, et surtout liaisons intersites.<\/p>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">Cette infrastructure permet&nbsp;de&nbsp;mieux relier&nbsp;leurs&nbsp;sites, leurs syst\u00e8mes&nbsp;d\u2019information&nbsp;et leurs services num\u00e9riques,&nbsp;tout en r\u00e9pondant aux exigences de performance propres au secteur de la sant\u00e9.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-6cd0bd1e img-block-right__text-container\">\n\n<h3 class=\"wp-block-heading block-text-right__subtitle mb-0\"><strong><strong>Garantir la disponibilit\u00e9 des services critiques<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">Dans un h\u00f4pital, une clinique, un laboratoire ou un centre d\u2019imagerie, la qualit\u00e9 de connexion conditionne directement la fluidit\u00e9 des parcours de soins.&nbsp;<\/p>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">Gr\u00e2ce \u00e0 son r\u00e9seau dense en \u00cele-de-France, d\u00e9ploy\u00e9 \u00e0 partir des infrastructures du m\u00e9tro et du RER, RATP Connect relie les sites de sant\u00e9 avec des liaisons Tr\u00e8s Haut D\u00e9bit adapt\u00e9es aux flux critiques et aux besoins de disponibilit\u00e9.<\/p>\n\n<\/div>\n\n<div class=\"gb-container gb-container-fc8aa65d img-block-right__text-container\">\n\n<h3 class=\"wp-block-heading block-text-right__subtitle mb-0\"><strong>Ma\u00eetriser la s\u00e9curit\u00e9 et l\u2019\u00e9volution des d\u00e9bits<\/strong><\/h3>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">La fibre optique noire offre aux \u00e9tablissements&nbsp;de sant\u00e9&nbsp;une infrastructure d\u00e9di\u00e9e, activable selon leurs besoins, avec une ma\u00eetrise renforc\u00e9e des d\u00e9bits, des \u00e9quipements et de la s\u00e9curit\u00e9 des \u00e9changes.<\/p>\n\n\n\n<p class=\"img-block-right__text wp-block-paragraph\">Elle constitue un socle robuste pour prot\u00e9ger les donn\u00e9es sensibles, absorber la mont\u00e9e en charge des usages&nbsp;num\u00e9riques et accompagner durablement la transformation num\u00e9rique de la sant\u00e9.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-b6e14c16 illu-background-container\">\n<div class=\"gb-container gb-container-c4218dca illu-background-topcover\"><\/div>\n\n\n<figure class=\"wp-block-image size-full illustration-background-circle\"><img decoding=\"async\" src=\"https:\/\/ratpconnect.com\/wp-content\/uploads\/2023\/12\/Forme_BG_Cercle_Right.svg\" alt=\"\" class=\"wp-image-3860\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full illustration-background-circle--opposite\"><img decoding=\"async\" src=\"https:\/\/ratpconnect.com\/wp-content\/uploads\/2024\/03\/Forme_BG_Cercle_Left.svg\" alt=\"\" class=\"wp-image-5460\"\/><\/figure>\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 Une connectivit\u00e9 critique au service de la continuit\u00e9 des soins RATP Connect accompagne les \u00e9tablissements de sant\u00e9 avec une infrastructure de fibre optique noire, con\u00e7ue pour soutenir les usages num\u00e9riques critiques, s\u00e9curiser les \u00e9changes de donn\u00e9es sensibles et garantir la continuit\u00e9 des services au &#8230; <a title=\"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9\" class=\"read-more\" href=\"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/\" aria-label=\"En savoir plus sur Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9\">Lire plus<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"parent":7487,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-7864","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect<\/title>\n<meta name=\"description\" content=\"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect\" \/>\n<meta property=\"og:description\" content=\"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"RATP Connect\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T08:14:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/\",\"url\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/\",\"name\":\"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ratpconnect.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg\",\"datePublished\":\"2026-07-02T07:40:44+00:00\",\"dateModified\":\"2026-07-02T08:14:36+00:00\",\"description\":\"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ratpconnect.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg\",\"contentUrl\":\"https:\\\/\\\/ratpconnect.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/ratpconnect.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos clients\",\"item\":\"https:\\\/\\\/ratpconnect.com\\\/nos-clients\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#website\",\"url\":\"https:\\\/\\\/ratpconnect.com\\\/\",\"name\":\"RATP Connect\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ratpconnect.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#organization\",\"name\":\"RATP Cap \u00cele-de-France\",\"url\":\"https:\\\/\\\/ratpconnect.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ratpconnect.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/LogosConnect.svg\",\"contentUrl\":\"https:\\\/\\\/ratpconnect.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/LogosConnect.svg\",\"caption\":\"RATP Cap \u00cele-de-France\"},\"image\":{\"@id\":\"https:\\\/\\\/ratpconnect.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect","description":"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect","og_description":"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.","og_url":"https:\/\/ratpconnect.com\/fr\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/","og_site_name":"RATP Connect","article_modified_time":"2026-07-02T08:14:36+00:00","og_image":[{"url":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/","url":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/","name":"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9 | RATP Connect","isPartOf":{"@id":"https:\/\/ratpconnect.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/#primaryimage"},"image":{"@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg","datePublished":"2026-07-02T07:40:44+00:00","dateModified":"2026-07-02T08:14:36+00:00","description":"RATP Connect accompagne les \u00e9tablissements de soin avec une fibre optique noire s\u00e9curis\u00e9e, \u00e9volutive et performante pour leurs \u00e9changes de donn\u00e9es.","breadcrumb":{"@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/#primaryimage","url":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg","contentUrl":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2026\/07\/Fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/ratpconnect.com\/nos-clients\/fibre-optique-noire-pour-les-etablissements-de-soin-et-de-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/ratpconnect.com\/"},{"@type":"ListItem","position":2,"name":"Nos clients","item":"https:\/\/ratpconnect.com\/nos-clients\/"},{"@type":"ListItem","position":3,"name":"Fibre optique noire pour les \u00e9tablissements de soin et de sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/ratpconnect.com\/#website","url":"https:\/\/ratpconnect.com\/","name":"RATP Connect","description":"","publisher":{"@id":"https:\/\/ratpconnect.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ratpconnect.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ratpconnect.com\/#organization","name":"RATP Cap \u00cele-de-France","url":"https:\/\/ratpconnect.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ratpconnect.com\/#\/schema\/logo\/image\/","url":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2024\/10\/LogosConnect.svg","contentUrl":"https:\/\/ratpconnect.com\/wp-content\/uploads\/2024\/10\/LogosConnect.svg","caption":"RATP Cap \u00cele-de-France"},"image":{"@id":"https:\/\/ratpconnect.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/pages\/7864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/comments?post=7864"}],"version-history":[{"count":4,"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/pages\/7864\/revisions"}],"predecessor-version":[{"id":7871,"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/pages\/7864\/revisions\/7871"}],"up":[{"embeddable":true,"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/pages\/7487"}],"wp:attachment":[{"href":"https:\/\/ratpconnect.com\/fr\/wp-json\/wp\/v2\/media?parent=7864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}